{"id":1115,"date":"2026-03-05T09:40:20","date_gmt":"2026-03-05T09:40:20","guid":{"rendered":"https:\/\/www.pmr-europe.com\/?post_type=ajde_events&#038;p=1115"},"modified":"2026-03-09T07:45:51","modified_gmt":"2026-03-09T07:45:51","slug":"la-colere-la-famille-et-la-mediation","status":"publish","type":"ajde_events","link":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/","title":{"rendered":"La col\u00e8re, la famille et la m\u00e9diation"},"content":{"rendered":"<p>Formation continue pour m\u00e9diateurs agr\u00e9\u00e9e par la CFM- Ouvert \u00e0 tous<\/p>\n<p>19 mai et 2 juin 2026<\/p>\n<p>Plus d&#8217;info? cliquez sur &#8220;info et inscription&#8221;<\/p>\n","protected":false},"author":2,"featured_media":-1,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"tags":[],"event_type":[20],"event_type_2":[],"class_list":["post-1115","ajde_events","type-ajde_events","status-publish","has-post-thumbnail","hentry","event_organizer-pmr-europe","event_type-formations-continues-et-supervision"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE<\/title>\n<meta name=\"description\" content=\"col\u00e8re famille m\u00e9diation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE\" \/>\n<meta property=\"og:description\" content=\"col\u00e8re famille m\u00e9diation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/\" \/>\n<meta property=\"og:site_name\" content=\"PMR EUROPE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T07:45:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/la-colere-la-famille-et-la-mediation\\\/\",\"url\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/la-colere-la-famille-et-la-mediation\\\/\",\"name\":\"La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#website\"},\"datePublished\":\"2026-03-05T09:40:20+00:00\",\"dateModified\":\"2026-03-09T07:45:51+00:00\",\"description\":\"col\u00e8re famille m\u00e9diation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/la-colere-la-famille-et-la-mediation\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/la-colere-la-famille-et-la-mediation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/la-colere-la-famille-et-la-mediation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La col\u00e8re, la famille et la m\u00e9diation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/\",\"name\":\"PMR EUROPE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#organization\",\"name\":\"pmr europe\",\"url\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pmr-europe.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-pmr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pmr-europe.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-pmr.jpg\",\"width\":1200,\"height\":601,\"caption\":\"pmr europe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pmr-europe.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE","description":"col\u00e8re famille m\u00e9diation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/","og_locale":"en_GB","og_type":"article","og_title":"La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE","og_description":"col\u00e8re famille m\u00e9diation","og_url":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/","og_site_name":"PMR EUROPE","article_modified_time":"2026-03-09T07:45:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/","url":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/","name":"La col\u00e8re, la famille et la m\u00e9diation - PMR EUROPE","isPartOf":{"@id":"https:\/\/www.pmr-europe.com\/en\/#website"},"datePublished":"2026-03-05T09:40:20+00:00","dateModified":"2026-03-09T07:45:51+00:00","description":"col\u00e8re famille m\u00e9diation","breadcrumb":{"@id":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmr-europe.com\/en\/events\/la-colere-la-famille-et-la-mediation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pmr-europe.com\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.pmr-europe.com\/en\/events\/"},{"@type":"ListItem","position":3,"name":"La col\u00e8re, la famille et la m\u00e9diation"}]},{"@type":"WebSite","@id":"https:\/\/www.pmr-europe.com\/en\/#website","url":"https:\/\/www.pmr-europe.com\/en\/","name":"PMR EUROPE","description":"","publisher":{"@id":"https:\/\/www.pmr-europe.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmr-europe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.pmr-europe.com\/en\/#organization","name":"pmr europe","url":"https:\/\/www.pmr-europe.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.pmr-europe.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.pmr-europe.com\/wp-content\/uploads\/2022\/06\/logo-pmr.jpg","contentUrl":"https:\/\/www.pmr-europe.com\/wp-content\/uploads\/2022\/06\/logo-pmr.jpg","width":1200,"height":601,"caption":"pmr europe"},"image":{"@id":"https:\/\/www.pmr-europe.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/ajde_events\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/comments?post=1115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/tags?post=1115"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/event_type?post=1115"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/www.pmr-europe.com\/en\/wp-json\/wp\/v2\/event_type_2?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}